{"id":14,"date":"2022-06-08T04:20:49","date_gmt":"2022-06-08T04:20:49","guid":{"rendered":"https:\/\/acsco.123websitedev.com\/?page_id=14"},"modified":"2025-09-06T16:02:38","modified_gmt":"2025-09-06T09:02:38","slug":"trang-chu","status":"publish","type":"page","link":"https:\/\/acsco.com.vn\/en\/","title":{"rendered":"Home page"},"content":{"rendered":"<div class=\"slider-wrapper relative\" id=\"slider-50334566\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{            \"cellAlign\": \"center\",            \"imagesLoaded\": true,            \"lazyLoad\": 1,            \"freeScroll\": false,            \"wrapAround\": true,            \"autoPlay\": 6000,            \"pauseAutoPlayOnHover\" : true,            \"prevNextButtons\": true,            \"contain\" : true,            \"adaptiveHeight\" : true,            \"dragThreshold\" : 10,            \"percentPosition\": true,            \"pageDots\": true,            \"rightToLeft\": false,            \"draggable\": true,            \"selectedAttraction\": 0.1,            \"parallax\" : 0,            \"friction\": 0.6        }'\n        >\n        \n\n  <div class=\"banner has-hover bg-fade-in bg-zoom-fade\" id=\"banner-1890241951\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill\"><\/div>\n                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1052018953\" class=\"text-box banner-layer x0 md-x0 lg-x0 y100 md-y100 lg-y100 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-left\">\n                  \n\t<div id=\"text-295507436\" class=\"text\">\n\t\t\n<h3>APPLICATION OF ROBOT IN WELDING LINE<\/h3>\n<p>Integrating Robot into automatic welding system<br \/>\n\t\t\n<style>\n#text-295507436 {\n  text-align: left;\n  color: rgb(255,255,255);\n}\n#text-295507436 > * {\n  color: rgb(255,255,255);\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/acsco.com.vn\/en\/danh-muc\/phu-kien-han-cat\/\" target=\"_self\" class=\"button secondary is-outline lowercase\"  >\n    <span>Click more<\/span>\n  <\/a>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1052018953 {\n  width: 60%;\n}\n#text-box-1052018953 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1890241951 {\n  padding-top: 40%;\n}\n#banner-1890241951 .bg.bg-loaded {\n  background-image: url(https:\/\/acsco.com.vn\/wp-content\/uploads\/2025\/06\/Ban-sao-cua-Mau-be-nhat-Thanh-lich-Trai-nghiem-Nghe-thuat-Trang-tri-Anh-bia-Facebook-4-2.png);\n}\n#banner-1890241951 .bg {\n  background-position: 56% 28%;\n}\n#banner-1890241951 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#banner-1890241951 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-384429471\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill\"><\/div>\n                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-2144502800\" class=\"text-box banner-layer x85 md-x85 lg-x85 y80 md-y80 lg-y80 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-left\">\n                  \n<a href=\"https:\/\/www.kjellberg.de\/catalog-details\/q-4500.html\" target=\"_self\" class=\"button secondary is-outline lowercase\"  >\n    <span>See more<\/span>\n  <\/a>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-2144502800 {\n  width: 60%;\n}\n#text-box-2144502800 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-384429471 {\n  padding-top: 40%;\n}\n#banner-384429471 .bg.bg-loaded {\n  background-image: url(https:\/\/acsco.com.vn\/wp-content\/uploads\/2025\/06\/Ban-sao-cua-Mau-be-nhat-Thanh-lich-Trai-nghiem-Nghe-thuat-Trang-tri-Anh-bia-Facebook-3-1.png);\n}\n#banner-384429471 .bg {\n  background-position: 5% 76%;\n}\n#banner-384429471 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#banner-384429471 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover bg-zoom-fade bg-fade-in\" id=\"banner-1681942511\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill\"><\/div>\n                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-364991515\" class=\"text-box banner-layer x0 md-x0 lg-x0 y15 md-y15 lg-y15 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h3 class=\"uppercase\">WELDING EQUIPMENT<\/h3>\n<a href=\"https:\/\/acsco.com.vn\/en\/danh-muc\/thiet-bi-han\/\" target=\"_self\" class=\"button white is-outline\"  >\n    <span>Click me<\/span>\n  <\/a>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-364991515 {\n  width: 60%;\n}\n#text-box-364991515 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-364991515 {\n    width: 40%;\n  }\n}\n<\/style>\n    <\/div>\n \n   <div id=\"text-box-898210701\" class=\"text-box banner-layer x0 md-x0 lg-x0 y15 md-y15 lg-y15 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h3 class=\"uppercase\">WELDING EQUIPMENT<\/h3>\n<a href=\"https:\/\/acsco.com.vn\/en\/danh-muc\/thiet-bi-han\/\" target=\"_self\" class=\"button white is-outline\"  >\n    <span>Click me<\/span>\n  <\/a>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-898210701 {\n  width: 60%;\n}\n#text-box-898210701 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-898210701 {\n    width: 40%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1681942511 {\n  padding-top: 40%;\n}\n#banner-1681942511 .bg.bg-loaded {\n  background-image: url(https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/welding_equipment-2-1-1024x486.png);\n}\n#banner-1681942511 .overlay {\n  background-color: rgba(0, 0, 0, 0.31);\n}\n#banner-1681942511 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#banner-1681942511 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover bg-fade-in bg-fade-out\" id=\"banner-1420851787\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill\"><\/div>\n                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-632136801\" class=\"text-box banner-layer x90 md-x90 lg-x90 y5 md-y5 lg-y5 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h3 class=\"uppercase\">SEAM TRACKING For Robotic<\/h3>\n<p>Solution for Welding Robotics<\/p>\n<a href=\"https:\/\/acsco.com.vn\/en\/danh-muc\/robot-han\/\" target=\"_self\" class=\"button white is-outline\"  >\n    <span>CLICK ME<\/span>\n  <\/a>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-632136801 {\n  width: 60%;\n}\n#text-box-632136801 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-632136801 {\n    width: 40%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1420851787 {\n  padding-top: 40%;\n}\n#banner-1420851787 .bg.bg-loaded {\n  background-image: url(https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/TH6_Seamtracking.jpg);\n}\n#banner-1420851787 .overlay {\n  background-color: rgba(0, 0, 0, 0.31);\n}\n#banner-1420851787 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#banner-1420851787 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-1773971983\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill\"><\/div>\n                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1074824624\" class=\"text-box banner-layer x50 md-x50 lg-x50 y80 md-y80 lg-y80 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\t<div id=\"text-2246088442\" class=\"text\">\n\t\t\n<h3 class=\"uppercase\"><strong>SOLUTIONS FOR PROGRAMMING COMPANIES<\/strong><\/h3>\n\t\t\n<style>\n#text-2246088442 {\n  line-height: 2.05;\n}\n<\/style>\n\t<\/div>\n\t\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1074824624 {\n  width: 60%;\n}\n#text-box-1074824624 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1773971983 {\n  padding-top: 40%;\n}\n#banner-1773971983 .bg.bg-loaded {\n  background-image: url(https:\/\/acsco.com.vn\/wp-content\/uploads\/2025\/06\/Ban-sao-cua-Mau-be-nhat-Thanh-lich-Trai-nghiem-Nghe-thuat-Trang-tri-Anh-bia-Facebook-10-1024x394.png);\n}\n#banner-1773971983 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#banner-1773971983 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-670656237\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill\"><\/div>\n                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-670656237 {\n  padding-top: 40%;\n}\n#banner-670656237 .bg.bg-loaded {\n  background-image: url(https:\/\/acsco.com.vn\/wp-content\/uploads\/2025\/09\/Ban-sao-cua-Mau-be-nhat-Thanh-lich-Trai-nghiem-Nghe-thuat-Trang-tri-Anh-bia-Facebook-1-1024x394.png);\n}\n#banner-670656237 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#banner-670656237 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-817278986\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill\"><\/div>\n                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-206630338\" class=\"text-box banner-layer x100 md-x100 lg-x100 y70 md-y70 lg-y70 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\t<div id=\"text-1368967150\" class=\"text\">\n\t\t\n<h3 class=\"uppercase\"><span style=\"color: #f99b1c;\"><b>CONSULTATION \u2013 REPAIR \u2013 INSTALLATION<\/b><\/span><\/h3>\n<p>Call us for a free quote.<\/p>\n\t\t\n<style>\n#text-1368967150 {\n  font-size: 1.4rem;\n}\n<\/style>\n\t<\/div>\n\t\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-206630338 {\n  width: 65%;\n}\n#text-box-206630338 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-817278986 {\n  padding-top: 40%;\n}\n#banner-817278986 .bg.bg-loaded {\n  background-image: url(https:\/\/acsco.com.vn\/wp-content\/uploads\/2025\/06\/Ban-sao-cua-Mau-be-nhat-Thanh-lich-Trai-nghiem-Nghe-thuat-Trang-tri-Anh-bia-Facebook-7-1024x394.png);\n}\n#banner-817278986 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#banner-817278986 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n  <\/div>\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n     \t<\/div>\n\n\n\t<section class=\"section\" id=\"section_1485726533\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1828228717\">\n\n\t<div id=\"col-623790326\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" ><h2 class=\"section-title section-title-normal\"><b><\/b><span class=\"section-title-main\" >About us<\/span><b><\/b><\/h2><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-623790326 > .col-inner {\n  margin: 50px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-279971292\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><strong>ACS Mechatronics Co., Ltd<\/strong> was established on the basis of modern technology with a team of engineers with many years of experience in the fields of welding, cutting, metal processing and automation.<br \/>With motto<span style=\"color: #f99b1c;\"><strong> \u201cBring the best solutions to customers\u201d<\/strong><\/span> We wish to bring the best values \u200b\u200bto you in terms of investment in production equipment and operating costs, contributing to your success and prosperous development.<br \/>Based on material and human resources,<strong> ACS<\/strong> We believe that we will bring to our customers the best solutions and the best technical services, contributing to the sustainable development of our customers. And that is also the success of our company.<\/p>\n\n  \n    <div class=\"row large-columns-3 medium-columns- small-columns-2\">\n  <div class=\"gallery-col col\" data-animate=\"fadeInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/welding_equipment-1024x486.png\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image image-zoom\" >\n                <img width=\"2224\" height=\"1056\" src=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/welding_equipment.png\" class=\"attachment-original size-original\" alt=\"\" loading=\"lazy\" ids=\"776,777,774\" columns=\"3\" animate=\"fadeInRight\" image_size=\"original\" image_hover=\"zoom\" srcset=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/welding_equipment.png 2224w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/welding_equipment-300x142.png 300w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/welding_equipment-1024x486.png 1024w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/welding_equipment-768x365.png 768w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/welding_equipment-1536x729.png 1536w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/welding_equipment-2048x972.png 2048w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/welding_equipment-16x8.png 16w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/welding_equipment-600x285.png 600w\" sizes=\"(max-width: 2224px) 100vw, 2224px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" data-animate=\"fadeInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/\u9996\u9801\u8f2a\u64ad\u80cc\u666f-drill_220105_01-1024x486.png\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image image-zoom\" >\n                <img width=\"2224\" height=\"1056\" src=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/\u9996\u9801\u8f2a\u64ad\u80cc\u666f-drill_220105_01.png\" class=\"attachment-original size-original\" alt=\"\" loading=\"lazy\" ids=\"776,777,774\" columns=\"3\" animate=\"fadeInRight\" image_size=\"original\" image_hover=\"zoom\" srcset=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/\u9996\u9801\u8f2a\u64ad\u80cc\u666f-drill_220105_01.png 2224w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/\u9996\u9801\u8f2a\u64ad\u80cc\u666f-drill_220105_01-300x142.png 300w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/\u9996\u9801\u8f2a\u64ad\u80cc\u666f-drill_220105_01-1024x486.png 1024w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/\u9996\u9801\u8f2a\u64ad\u80cc\u666f-drill_220105_01-768x365.png 768w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/\u9996\u9801\u8f2a\u64ad\u80cc\u666f-drill_220105_01-1536x729.png 1536w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/\u9996\u9801\u8f2a\u64ad\u80cc\u666f-drill_220105_01-2048x972.png 2048w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/\u9996\u9801\u8f2a\u64ad\u80cc\u666f-drill_220105_01-16x8.png 16w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/\u9996\u9801\u8f2a\u64ad\u80cc\u666f-drill_220105_01-600x285.png 600w\" sizes=\"(max-width: 2224px) 100vw, 2224px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" data-animate=\"fadeInRight\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/welding_equipment-2-1024x486.png\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image image-zoom\" >\n                <img width=\"2224\" height=\"1056\" src=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/welding_equipment-2.png\" class=\"attachment-original size-original\" alt=\"\" loading=\"lazy\" ids=\"776,777,774\" columns=\"3\" animate=\"fadeInRight\" image_size=\"original\" image_hover=\"zoom\" srcset=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/welding_equipment-2.png 2224w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/welding_equipment-2-300x142.png 300w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/welding_equipment-2-1024x486.png 1024w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/welding_equipment-2-768x365.png 768w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/welding_equipment-2-1536x729.png 1536w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/welding_equipment-2-2048x972.png 2048w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/welding_equipment-2-16x8.png 16w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/welding_equipment-2-600x285.png 600w\" sizes=\"(max-width: 2224px) 100vw, 2224px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-279971292 > .col-inner {\n  margin: 45px 0px -5px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1485726533 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n#section_1485726533 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_1485726533 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_737433386\">\n\t\t<div class=\"bg section-bg fill bg-fill\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-944266889\">\n\n\t<div id=\"col-1571772330\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" ><h2 class=\"section-title section-title-normal\"><b><\/b><span class=\"section-title-main\" >Solution<\/span><b><\/b><\/h2><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1571772330 > .col-inner {\n  margin: 50px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1998085298\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n    <div id=\"content\" class=\"content-area page-wrapper\" role=\"main\">\n        <div class=\"row  large-columns-3 medium-columns-1 small-columns-1\">\n                                <div class=\"col post-item\">\n                        <div class=\"col-inner\">\n                            <a href=\"https:\/\/acsco.com.vn\/en\/giai-phap\/robot-han-laser-giai-phap-han-tu-dong-chinh-xac-nhanh-va-tiet-kiem\/\" class=\"plain\">\n                                <div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n                                    <div class=\"box-image custom-img-top-sp\">\n                                        <div class=\"image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                                            <\/div>\n                                    <\/div>\n                                    <div class=\"custom-box box-text text-left\">\n                                        <div class=\"box-text-inner blog-post-inner\">\n\n\n                                            <h5 class=\"custom-blog post-title is-large\">Robot H\u00e0n Laser \u2013 Gi\u1ea3i Ph\u00e1p H\u00e0n T\u1ef1 \u0110\u1ed9ng Ch\u00ednh X\u00e1c, Nhanh v\u00e0 Ti\u1ebft Ki\u1ec7m<\/h5>\n                                            <div class=\"post-meta is-small op-8\">19\/08\/2025<\/div>\t\t\t\t\t<div class=\"is-divider\"><\/div>\n                                            <p class=\"from_the_blog_excerpt\"><p>H\u00e0n laser l\u00e0 c\u00f4ng ngh\u1ec7 h\u00e0n hi\u1ec7n \u0111\u1ea1i s\u1eed d\u1ee5ng tia laser c\u01b0\u1eddng \u0111\u1ed9 cao&#8230;<\/p>\n<\/p>\n\n\n\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/a>\n                        <\/div>\n                    <\/div>\n\n\n\n                                        <div class=\"col post-item\">\n                        <div class=\"col-inner\">\n                            <a href=\"https:\/\/acsco.com.vn\/en\/giai-phap\/robot-han\/\" class=\"plain\">\n                                <div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n                                    <div class=\"box-image custom-img-top-sp\">\n                                        <div class=\"image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                                            <img width=\"2000\" height=\"1575\" src=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/480-x-378-mm-480-x-378-mm-4.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/480-x-378-mm-480-x-378-mm-4.png 2000w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/480-x-378-mm-480-x-378-mm-4-300x236.png 300w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/480-x-378-mm-480-x-378-mm-4-1024x806.png 1024w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/480-x-378-mm-480-x-378-mm-4-768x605.png 768w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/480-x-378-mm-480-x-378-mm-4-1536x1210.png 1536w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/480-x-378-mm-480-x-378-mm-4-16x12.png 16w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/480-x-378-mm-480-x-378-mm-4-600x473.png 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/div>\n                                    <\/div>\n                                    <div class=\"custom-box box-text text-left\">\n                                        <div class=\"box-text-inner blog-post-inner\">\n\n\n                                            <h5 class=\"custom-blog post-title is-large\">Welding robot<\/h5>\n                                            <div class=\"post-meta is-small op-8\">23\/06\/2022<\/div>\t\t\t\t\t<div class=\"is-divider\"><\/div>\n                                            <p class=\"from_the_blog_excerpt\"><p>Solutions for all cutting needs Our worldwide partners\u2026<\/p>\n<\/p>\n\n\n\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/a>\n                        <\/div>\n                    <\/div>\n\n\n\n                                        <div class=\"col post-item\">\n                        <div class=\"col-inner\">\n                            <a href=\"https:\/\/acsco.com.vn\/en\/giai-phap\/may-cat-cnc\/\" class=\"plain\">\n                                <div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n                                    <div class=\"box-image custom-img-top-sp\">\n                                        <div class=\"image-zoom image-cover\" style=\"padding-top:56.25%;\">\n                                            <img width=\"2000\" height=\"1575\" src=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/480-x-378-mm-480-x-378-mm-3.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/480-x-378-mm-480-x-378-mm-3.png 2000w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/480-x-378-mm-480-x-378-mm-3-300x236.png 300w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/480-x-378-mm-480-x-378-mm-3-1024x806.png 1024w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/480-x-378-mm-480-x-378-mm-3-768x605.png 768w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/480-x-378-mm-480-x-378-mm-3-1536x1210.png 1536w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/480-x-378-mm-480-x-378-mm-3-16x12.png 16w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/480-x-378-mm-480-x-378-mm-3-600x473.png 600w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/div>\n                                    <\/div>\n                                    <div class=\"custom-box box-text text-left\">\n                                        <div class=\"box-text-inner blog-post-inner\">\n\n\n                                            <h5 class=\"custom-blog post-title is-large\">CNC<\/h5>\n                                            <div class=\"post-meta is-small op-8\">09\/06\/2022<\/div>\t\t\t\t\t<div class=\"is-divider\"><\/div>\n                                            <p class=\"from_the_blog_excerpt\"><p>Solutions for all cutting needs Our worldwide partners\u2026<\/p>\n<\/p>\n\n\n\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/a>\n                        <\/div>\n                    <\/div>\n\n\n\n                            <\/div>\n    <\/div>\n    \n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1998085298 > .col-inner {\n  margin: 20px 0px -35px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_737433386 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n#section_737433386 .section-bg.bg-loaded {\n  background-image: url(https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/bg-01.jpg);\n}\n#section_737433386 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_737433386 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1276349500\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-25409388\">\n\n\t<div id=\"col-309333646\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" ><h2 class=\"section-title section-title-normal\"><b><\/b><span class=\"section-title-main\" >Product<\/span><b><\/b><\/h2><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-309333646 > .col-inner {\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-740523494\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:px 0px 0px 0px;\">\n\t<\/div>\n\t\t\t\n<div class=\"slider-wrapper relative\" id=\"slider-857658369\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{            \"cellAlign\": \"center\",            \"imagesLoaded\": true,            \"lazyLoad\": 1,            \"freeScroll\": false,            \"wrapAround\": true,            \"autoPlay\": 6000,            \"pauseAutoPlayOnHover\" : true,            \"prevNextButtons\": true,            \"contain\" : true,            \"adaptiveHeight\" : true,            \"dragThreshold\" : 10,            \"percentPosition\": true,            \"pageDots\": true,            \"rightToLeft\": false,            \"draggable\": true,            \"selectedAttraction\": 0.1,            \"parallax\" : 0,            \"friction\": 0.6        }'\n        >\n        \n<div class=\"row\"  id=\"row-497345199\">\n\n\t<div id=\"col-1798928649\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"row\"  id=\"row-62334328\">\n\n\t<div id=\"col-477115136\" class=\"col small-12 large-12\"  data-animate=\"fadeInRight\">\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n<div class=\"woocommerce columns-1\"><div class=\"products row row-small large-columns-1 medium-columns-2 small-columns-1\">\n<div class=\"product-small col has-hover product type-product post-822 status-publish first instock product_cat-kuka product_cat-robot-han has-post-thumbnail shipping-taxable product-type-simple\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n<\/div>\n\t<div class=\"product-small box\">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"custom-img-sp image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/acsco.com.vn\/en\/product\/kuka-robot\/\" aria-label=\"KUKA Robot\">\n\t\t\t\t\t<img width=\"300\" height=\"300\" src=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/Kuka-Kr-Cybertech-Nano-Arc-Welding-Robot-China-Industrial-Robot-Arm-and-Robot-Handing-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/Kuka-Kr-Cybertech-Nano-Arc-Welding-Robot-China-Industrial-Robot-Arm-and-Robot-Handing-300x300.jpg 300w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/Kuka-Kr-Cybertech-Nano-Arc-Welding-Robot-China-Industrial-Robot-Arm-and-Robot-Handing-150x150.jpg 150w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/Kuka-Kr-Cybertech-Nano-Arc-Welding-Robot-China-Industrial-Robot-Arm-and-Robot-Handing-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text custom-txt-sp box-text-products\">\n\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tKUKA\t\t<\/p>\n\t<\/div><div class=\"price-wrapper\"><\/div>\t\t<\/div>\n\t<\/div>\n\t\t<\/div>\n<\/div><\/div><!-- row --><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1113290312\" class=\"col medium-4 small-12 large-4\"  data-animate=\"fadeInRight\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"woocommerce columns-1\"><div class=\"products row row-small large-columns-1 medium-columns-2 small-columns-1\">\n<div class=\"product-small col has-hover product type-product post-1016 status-publish first instock product_cat-robot-han has-post-thumbnail shipping-taxable product-type-simple\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n<\/div>\n\t<div class=\"product-small box\">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"custom-img-sp image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/acsco.com.vn\/en\/product\/he-thong-robot-han\/\" aria-label=\"H\u1ec6 TH\u1ed0NG ROBOT H\u00c0N\">\n\t\t\t\t\t<img width=\"300\" height=\"300\" src=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2025\/06\/weld-robot-300x300.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2025\/06\/weld-robot-300x300.png 300w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2025\/06\/weld-robot-150x150.png 150w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2025\/06\/weld-robot-100x100.png 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text custom-txt-sp box-text-products\">\n\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tRobot\t\t<\/p>\n\t<\/div><div class=\"price-wrapper\"><\/div>\t\t<\/div>\n\t<\/div>\n\t\t<\/div>\n<\/div><\/div><!-- row --><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-983004618\" class=\"col medium-4 small-12 large-4\"  data-animate=\"fadeInRight\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row\"  id=\"row-1832940925\">\n\n\t<div id=\"col-1436037702\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"woocommerce columns-1\"><div class=\"products row row-small large-columns-1 medium-columns-2 small-columns-1\">\n<div class=\"product-small col has-hover product type-product post-1003 status-publish first instock product_cat-cobot-robot-han has-post-thumbnail shipping-taxable product-type-simple\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n<\/div>\n\t<div class=\"product-small box\">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"custom-img-sp image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/acsco.com.vn\/en\/product\/cobot-hang-duco\/\" aria-label=\"COBOT H\u00c0N DUCO\">\n\t\t\t\t\t<img width=\"300\" height=\"300\" src=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2025\/06\/Cubot-1-300x300.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2025\/06\/Cubot-1-300x300.png 300w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2025\/06\/Cubot-1-150x150.png 150w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2025\/06\/Cubot-1-100x100.png 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img width=\"300\" height=\"300\" src=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2025\/06\/Cubot-300x300.png\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2025\/06\/Cubot-300x300.png 300w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2025\/06\/Cubot-150x150.png 150w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2025\/06\/Cubot-100x100.png 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text custom-txt-sp box-text-products\">\n\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tCobot\t\t<\/p>\n\t<\/div><div class=\"price-wrapper\"><\/div>\t\t<\/div>\n\t<\/div>\n\t\t<\/div>\n<\/div><\/div><!-- row --><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n     \t<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-740523494 > .col-inner {\n  margin: 50px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1276349500 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n#section_1276349500 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_1276349500 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1804336191\">\n\t\t<div class=\"bg section-bg fill bg-fill\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1356808859\">\n\n\t<div id=\"col-384871556\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" ><h2 class=\"section-title section-title-normal\"><b><\/b><span class=\"section-title-main\" >News<\/span><b><\/b><\/h2><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-384871556 > .col-inner {\n  margin: 60px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1405177425\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  \n    <div class=\"row custom-blog large-columns-3 medium-columns-1 small-columns-1 has-shadow row-box-shadow-1 slider row-slider slider-nav-simple slider-nav-outside slider-nav-push\"  data-flickity-options='{\"imagesLoaded\": true, \"groupCells\": \"100%\", \"dragThreshold\" : 5, \"cellAlign\": \"left\",\"wrapAround\": true,\"prevNextButtons\": true,\"percentPosition\": true,\"pageDots\": false, \"rightToLeft\": false, \"autoPlay\" : false}'>\n\n  <div class=\"col post-item\" data-animate=\"fadeInRight\">\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/acsco.com.vn\/en\/cong-nghe-laser-co2-va-fiber-su-lua-chon-nao-phu-hop-cho-ban\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image custom-img-top-sp\" >\n  \t\t\t\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:56.25%;\">\n  \t\t\t\t\t\t\t<img width=\"907\" height=\"674\" src=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/laser1.png\" class=\"attachment-original size-original wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/laser1.png 907w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/laser1-300x223.png 300w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/laser1-768x571.png 768w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/laser1-16x12.png 16w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/laser1-600x446.png 600w\" sizes=\"(max-width: 907px) 100vw, 907px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">CO2 and Fiber laser technology, which choice is right for you?<\/h5>\n\t\t\t\t\t<div class=\"post-meta is-small op-8\">19\/05\/2023<\/div>\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt\">The development of Laser Fiber technology Fiber laser cutting is one of the...\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" data-animate=\"fadeInRight\">\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/acsco.com.vn\/en\/so-sanh-cong-nghe-true-hole-va-contour-cut\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image custom-img-top-sp\" >\n  \t\t\t\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:56.25%;\">\n  \t\t\t\t\t\t\t<img width=\"594\" height=\"334\" src=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/10\/Representative_v1.jpg\" class=\"attachment-original size-original wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/10\/Representative_v1.jpg 594w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/10\/Representative_v1-300x169.jpg 300w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/10\/Representative_v1-16x9.jpg 16w\" sizes=\"(max-width: 594px) 100vw, 594px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">Compare True Hole and Contour Cut technology<\/h5>\n\t\t\t\t\t<div class=\"post-meta is-small op-8\">19\/10\/2022<\/div>\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt\">True Hole Technology: (Hypertherm Source) Introduction: part of SureCut......\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" data-animate=\"fadeInRight\">\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/acsco.com.vn\/en\/cong-nghe-laser\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image custom-img-top-sp\" >\n  \t\t\t\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:56.25%;\">\n  \t\t\t\t\t\t\t<img width=\"1000\" height=\"500\" src=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/laser_rep.jpg\" class=\"attachment-original size-original wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/laser_rep.jpg 1000w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/laser_rep-300x150.jpg 300w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/laser_rep-768x384.jpg 768w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/laser_rep-16x8.jpg 16w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/laser_rep-600x300.jpg 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">Laser Technology<\/h5>\n\t\t\t\t\t<div class=\"post-meta is-small op-8\">09\/06\/2022<\/div>\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt\">Laser Technology Concepts There are many applications for metalworking, in...\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" data-animate=\"fadeInRight\">\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/acsco.com.vn\/en\/cong-nghe-plasma\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image custom-img-top-sp\" >\n  \t\t\t\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:56.25%;\">\n  \t\t\t\t\t\t\t<img width=\"250\" height=\"266\" src=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/cong-nghe-plasma.jpg\" class=\"attachment-original size-original wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/cong-nghe-plasma.jpg 250w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/cong-nghe-plasma-11x12.jpg 11w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">Plasma Technology<\/h5>\n\t\t\t\t\t<div class=\"post-meta is-small op-8\">09\/06\/2022<\/div>\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt\">1.What is Plasma? Plasma is the fourth state of matter. We often......\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" data-animate=\"fadeInRight\">\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/acsco.com.vn\/en\/gioi-thieu-cac-thiet-bi-dong-cat-va-pham-vi-ung-dung-cua-moi-loai\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image custom-img-top-sp\" >\n  \t\t\t\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:56.25%;\">\n  \t\t\t\t\t\t\t<img width=\"300\" height=\"300\" src=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/Thiet-bi-dong-cat-1-300x300-1.jpg\" class=\"attachment-original size-original wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/Thiet-bi-dong-cat-1-300x300-1.jpg 300w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/Thiet-bi-dong-cat-1-300x300-1-150x150.jpg 150w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/Thiet-bi-dong-cat-1-300x300-1-12x12.jpg 12w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/Thiet-bi-dong-cat-1-300x300-1-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">Introduction of switchgear and their range of applications<\/h5>\n\t\t\t\t\t<div class=\"post-meta is-small op-8\">09\/06\/2022<\/div>\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt\">Introduction of switchgear and the range of applications of each type \u2013 Equipment...\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" data-animate=\"fadeInRight\">\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/acsco.com.vn\/en\/nguyen-ly-van-hanh-cua-tia-laser-khi-cat-kim-loai\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image custom-img-top-sp\" >\n  \t\t\t\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:56.25%;\">\n  \t\t\t\t\t\t\t<img width=\"1400\" height=\"788\" src=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/56-131.jpg\" class=\"attachment-original size-original wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/56-131.jpg 1400w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/56-131-300x169.jpg 300w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/56-131-1024x576.jpg 1024w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/56-131-768x432.jpg 768w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/56-131-18x10.jpg 18w, https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/56-131-600x338.jpg 600w\" sizes=\"(max-width: 1400px) 100vw, 1400px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">Working principle of laser when cutting metal<\/h5>\n\t\t\t\t\t<div class=\"post-meta is-small op-8\">09\/06\/2022<\/div>\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt\">Laser metal cutting has been used to produce standard cuts....\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1405177425 > .col-inner {\n  margin: 60px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1804336191 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n#section_1804336191 .section-bg.bg-loaded {\n  background-image: url(https:\/\/acsco.com.vn\/wp-content\/uploads\/2022\/06\/bg-01.jpg);\n}\n#section_1804336191 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_1804336191 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1263099182\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1288727005\">\n\n\t<div id=\"col-1173273218\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" ><h2 class=\"section-title section-title-normal\"><b><\/b><span class=\"section-title-main\" >Partner<\/span><b><\/b><\/h2><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1173273218 > .col-inner {\n  margin: 50px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-987476736\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"slider-wrapper relative\" id=\"slider-1066259109\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{            \"cellAlign\": \"left\",            \"imagesLoaded\": true,            \"lazyLoad\": 1,            \"freeScroll\": false,            \"wrapAround\": true,            \"autoPlay\": 3000,            \"pauseAutoPlayOnHover\" : true,            \"prevNextButtons\": false,            \"contain\" : true,            \"adaptiveHeight\" : true,            \"dragThreshold\" : 10,            \"percentPosition\": true,            \"pageDots\": false,            \"rightToLeft\": false,            \"draggable\": true,            \"selectedAttraction\": 0.1,            \"parallax\" : 0,            \"friction\": 0.6        }'\n        >\n        \n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 100px!important\"><div class=\"ux-logo-link block image-zoom\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img src=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/Logo_proarc.jpg\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:70px;\" \/><\/div><\/div>\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 241.62790697674px!important\"><div class=\"ux-logo-link block image-zoom\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img src=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/Logo_GElb.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:70px;\" \/><\/div><\/div>\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 105.50925925926px!important\"><div class=\"ux-logo-link block image-\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img src=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/Logo_gys.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:70px;\" \/><\/div><\/div>\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 342.6256281407px!important\"><div class=\"ux-logo-link block image-\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img src=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/KUKA_logo.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:70px;\" \/><\/div><\/div>\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 280.23255813953px!important\"><div class=\"ux-logo-link block image-\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img src=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/logo_thermacut.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:50px;\" \/><\/div><\/div>\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 80px!important\"><div class=\"ux-logo-link block image-\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img src=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/Logo_asuzac.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:50px;\" \/><\/div><\/div>\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 122.57425742574px!important\"><div class=\"ux-logo-link block image-\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img src=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/Logo_posco.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:50px;\" \/><\/div><\/div>\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 924.44444444444px!important\"><div class=\"ux-logo-link block image-\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img src=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2023\/05\/Logo_Eckelmann.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:70px;\" \/><\/div><\/div>\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 210px!important\"><div class=\"ux-logo-link block image-\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img src=\"https:\/\/acsco.com.vn\/wp-content\/uploads\/2025\/06\/hypertherm-inc-logo-vector.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:100px;\" \/><\/div><\/div>\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n     \t<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-987476736 > .col-inner {\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1263099182 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n#section_1263099182 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_1263099182 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"row\"  id=\"row-1195500659\">\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v15.9.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C\u00f4ng Ty TNHH C\u01a1 \u0110i\u1ec7n T\u1eed ACS - Mang \u0111\u1ebfn b\u1ea1n gi\u1ea3i ph\u00e1p t\u1ed1t nh\u1ea5t<\/title>\n<meta name=\"description\" content=\"Chuy\u00ean cung c\u1ea5p gi\u1ea3i ph\u00e1p h\u00e0n c\u1eaft kim lo\u1ea1i, \u1ee9ng d\u1ee5ng t\u1ef1 \u0111\u1ed9ng h\u00f3a v\u00e0o s\u1ea3n xu\u1ea5t\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acsco.com.vn\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f4ng Ty TNHH C\u01a1 \u0110i\u1ec7n T\u1eed ACS - Mang \u0111\u1ebfn b\u1ea1n gi\u1ea3i ph\u00e1p t\u1ed1t nh\u1ea5t\" \/>\n<meta property=\"og:description\" content=\"Chuy\u00ean cung c\u1ea5p gi\u1ea3i ph\u00e1p h\u00e0n c\u1eaft kim lo\u1ea1i, \u1ee9ng d\u1ee5ng t\u1ef1 \u0111\u1ed9ng h\u00f3a v\u00e0o s\u1ea3n xu\u1ea5t\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acsco.com.vn\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"C\u00f4ng Ty TNHH C\u01a1 \u0110i\u1ec7n T\u1eed ACS\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-06T09:02:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data1\" content=\"2 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/acsco.com.vn\/#website\",\"url\":\"https:\/\/acsco.com.vn\/\",\"name\":\"C\\u00f4ng Ty TNHH C\\u01a1 \\u0110i\\u1ec7n T\\u1eed ACS\",\"description\":\"Give you the best solution !!!!!!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/acsco.com.vn\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/acsco.com.vn\/#webpage\",\"url\":\"https:\/\/acsco.com.vn\/\",\"name\":\"C\\u00f4ng Ty TNHH C\\u01a1 \\u0110i\\u1ec7n T\\u1eed ACS - Mang \\u0111\\u1ebfn b\\u1ea1n gi\\u1ea3i ph\\u00e1p t\\u1ed1t nh\\u1ea5t\",\"isPartOf\":{\"@id\":\"https:\/\/acsco.com.vn\/#website\"},\"datePublished\":\"2022-06-08T04:20:49+00:00\",\"dateModified\":\"2025-09-06T09:02:38+00:00\",\"description\":\"Chuy\\u00ean cung c\\u1ea5p gi\\u1ea3i ph\\u00e1p h\\u00e0n c\\u1eaft kim lo\\u1ea1i, \\u1ee9ng d\\u1ee5ng t\\u1ef1 \\u0111\\u1ed9ng h\\u00f3a v\\u00e0o s\\u1ea3n xu\\u1ea5t\",\"breadcrumb\":{\"@id\":\"https:\/\/acsco.com.vn\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/acsco.com.vn\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/acsco.com.vn\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/acsco.com.vn\/\",\"url\":\"https:\/\/acsco.com.vn\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/acsco.com.vn\/\",\"url\":\"https:\/\/acsco.com.vn\/\",\"name\":\"Trang ch\\u1ee7\"}}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","_links":{"self":[{"href":"https:\/\/acsco.com.vn\/en\/wp-json\/wp\/v2\/pages\/14"}],"collection":[{"href":"https:\/\/acsco.com.vn\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/acsco.com.vn\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/acsco.com.vn\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acsco.com.vn\/en\/wp-json\/wp\/v2\/comments?post=14"}],"version-history":[{"count":165,"href":"https:\/\/acsco.com.vn\/en\/wp-json\/wp\/v2\/pages\/14\/revisions"}],"predecessor-version":[{"id":1701,"href":"https:\/\/acsco.com.vn\/en\/wp-json\/wp\/v2\/pages\/14\/revisions\/1701"}],"wp:attachment":[{"href":"https:\/\/acsco.com.vn\/en\/wp-json\/wp\/v2\/media?parent=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}